{"id":30771,"date":"2024-11-21T10:42:38","date_gmt":"2024-11-21T10:42:38","guid":{"rendered":"https:\/\/bicycles4ever.com\/en\/off-script-november-camp-2024-from-medicals-to-manchester-united\/"},"modified":"2024-11-21T10:42:38","modified_gmt":"2024-11-21T10:42:38","slug":"off-script-november-camp-2024-from-medicals-to-manchester-united","status":"publish","type":"post","link":"https:\/\/bicycles4ever.com\/en\/off-script-november-camp-2024-from-medicals-to-manchester-united\/","title":{"rendered":"Off-Script November Camp 2024 | From Medicals to Manchester United"},"content":{"rendered":"<h2>Off-Script November Camp 2024 | From Medicals to Manchester United<\/h2>\n<p><iframe loading=\"lazy\" title=\"Off-Script November Camp 2024 | From Medicals to Manchester United\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/BVqSSWVxu0M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nSource: <strong><a href=\"https:\/\/www.youtube.com\/watch?v=BVqSSWVxu0M\" rel=\"nofollow noopener\" target=\"_blank\">Ineos Grenadiers Youtube Channel: Off-Script November Camp 2024 | From Medicals to Manchester United<\/a><\/strong><\/p>\n<h3>Video Off-Script November Camp 2024 | From Medicals to Manchester United with Ineos Grenadiers Team<\/h3>\n<p>Video <strong>Off-Script November Camp 2024 | From Medicals to Manchester United<\/strong> with <strong><a href=\"https:\/\/bicycles4ever.com\/en\/tag\/ineos-grenadiers\/\">Ineos Grenadiers<\/a><\/strong> YouTube Channel.<\/p>\n<h2>Off-Script November Camp 2024 | From Medicals to Manchester United<\/h2>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>The opinions expressed in this space are the sole responsibility of the <strong>YouTube Channel <a href=\"https:\/\/bicycles4ever.com\/en\/tag\/ineos-grenadiers\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ineos Grenadiers<\/a><\/strong> and do not necessarily represent the views of <strong><a href=\"https:\/\/bicycles4ever.com\/en\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/bicycles4ever.com\/en\/\" rel=\"noreferrer noopener\">CicloNews<\/a><\/strong>.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Bicycles4ever<\/span><\/p><\/nav>\n","protected":false},"excerpt":{"rendered":"<p>Off-Script November Camp 2024 | From Medicals to Manchester United Source: Ineos Grenadiers Youtube Channel: Off-Script November Camp 2024 | From Medicals to Manchester United Video Off-Script November Camp 2024 | From Medicals to Manchester United with Ineos Grenadiers Team Video Off-Script November Camp 2024 | From Medicals to Manchester United with Ineos Grenadiers YouTube [&#8230;]\n","protected":false},"author":2,"featured_media":30773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_1742903173470134272_1742903173470134272":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","_trash_the_other_posts":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"editor_notices":[],"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[131],"class_list":["post-30771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-road","tag-ineos-grenadiers"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/bicycles4ever.com\/en\/wp-content\/uploads\/sites\/3\/2024\/11\/Off-Script-November-Camp-2024-From-Medicals-to-Manchester-United.jpg","_links":{"self":[{"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/posts\/30771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/comments?post=30771"}],"version-history":[{"count":0,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/posts\/30771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/media\/30773"}],"wp:attachment":[{"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/media?parent=30771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/categories?post=30771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bicycles4ever.com\/en\/wp-json\/wp\/v2\/tags?post=30771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}